{"id":6314,"date":"2015-03-03T14:19:12","date_gmt":"2015-03-03T13:19:12","guid":{"rendered":"https:\/\/www.thierryregards.eu\/2019\/02\/rdc-pai-la-cooperation-belge-au-developpement-arnaquee-copy\/"},"modified":"2024-08-02T10:09:18","modified_gmt":"2024-08-02T08:09:18","slug":"rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest","status":"publish","type":"post","link":"https:\/\/thierryregards.eu\/en\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/","title":{"rendered":"RDC &#8211; PAI &#8211; Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &#038; Cie"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><div class=\"x-section e6314-e1 m4ve-0\"><div class=\"x-container max width e6314-e2 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e3 m4ve-4\"><div class=\"x-text x-content e6314-e4 m4ve-7\"><h1><span style=\"color: #800000; font-size: 42px;\">Les porteurs du projet&nbsp;&laquo; D&eacute;pendance alimentaire &raquo;<\/span><\/h1><\/div><div class=\"x-text x-content e6314-e5 m4ve-7\"><div id=\"x-content-band-1\" class=\"x-content-band bg-image parallax border-top border-left border-right border-bottom\" data-x-element=\"content_band\" data-x-params=\"{&quot;type&quot;:&quot;image&quot;,&quot;parallax&quot;:true}\" style=\"background-image: url(http:\/\/thierryregards.eu\/wp-content\/uploads\/2015\/06\/060212-104.jpg); background-color: transparent; color: #fff;\"><div class=\"x-container max width\"><span style=\"color: #ffff00;\"><strong>La cr\u00e9ation des parcs agro industriels est <\/strong><\/span><strong>LA<\/strong><span style=\"color: #ffff00;\"><strong> solution au probl\u00e8me de souverainet\u00e9 alimentaire envisag\u00e9e par le Pr\u00e9sident Joseph Kabila et son Premier ministre, Matata Ponyo.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff6600;\"><strong>Le probl\u00e8me avec l\u2019agro-industrie est\u00a0:<\/strong><\/span><\/p>\n<ul>\n\t<li style=\"text-align: justify;\"><span style=\"color: #ffff00;\"><strong>Qu\u2019elle utilise des OGM<\/strong><\/span>, des intrants chimiques et quantit\u00e9s d\u2019additifs dont l\u2019impact n\u00e9gatif sur la justice sociale, l\u2019\u00e9conomie, l\u2019environnement, la sant\u00e9, est de plus en plus \u00e9vident.<\/li>\n\t<li style=\"text-align: justify;\"><span style=\"color: #ffff00;\"><strong>Qu\u2019elle oblige tout agriculteur<\/strong> <\/span>\u00e0 acheter des semences OGM ou hybrides, des intrants chimiques non renouvelables, du mat\u00e9riel et des technologies \u00e9trang\u00e8res, etc. Un autre paradoxe lorsqu'il est question de souverainet\u00e9 alimentaire !<\/li>\n\t<li style=\"text-align: justify;\"><strong><span style=\"color: #ffff00;\">Qu\u2019elle expulse les agriculteurs<\/span><\/strong> vers les villes<\/div><\/div><\/div><div class=\"x-text x-content e6314-e6 m4ve-7\"><p style=\"color: #05013c; text-align: justify;\">Cette d&eacute;pendance est organis&eacute;e par des transnationales aujourd&rsquo;hui plus puissantes que les Etats dont le but est la rentabilit&eacute; financi&egrave;re, entendez, le versement de&nbsp;hauts salaires et de&nbsp;dividendes distribu&eacute;s hors RDC au profit des &laquo;&nbsp;investisseurs&nbsp;&raquo;&hellip;&nbsp;<strong>En voici quelques facettes.<\/strong><\/p>\n<p style=\"color: #05013c; text-align: justify;\">Au fur et &agrave; mesure des recherches sur l&rsquo;agro-industrie en RDC, je d&eacute;couvre d&rsquo;autres &eacute;l&eacute;ments &eacute;tonnants : la &laquo;&nbsp;r&eacute;volution de la modernit&eacute;&nbsp;&raquo; est le fait des lobbies de l&rsquo;agro-alimentaire et des&nbsp;structures politiques qu&rsquo;elles soutiennent !<\/p><\/div><hr class=\"x-line e6314-e7 m4ve-8 m4ve-9\"\/><\/div><\/div><div class=\"x-container max width e6314-e8 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-5 e6314-e9 m4ve-4 m4ve-5\"><span class=\"x-image e6314-e10 m4ve-c\"><img decoding=\"async\" src=\"https:\/\/www.thierryregards.eu\/wp-content\/uploads\/2015\/12\/COMESA.jpg\" width=\"145\" height=\"137\" alt=\"Image\" loading=\"lazy\"><\/span><\/div><div class=\"x-column x-sm x-4-5 e6314-e11 m4ve-4\"><div class=\"x-text x-content e6314-e12 m4ve-7\"><p style=\"text-align: justify;\"><strong style=\"color: #05013c; text-align: justify;\">Exemple. Vous connaissez le COMESA\u00a0?<\/strong><span style=\"color: #05013c; text-align: justify;\">\u00a0La vision du\u00a0<\/span><a style=\"text-align: justify;\" href=\"http:\/\/www.comesa.int\/\" target=\"_blank\" rel=\"noopener\">COMESA<\/a><span style=\"color: #05013c; text-align: justify;\">\u00a0pour\u00a0<\/span><em style=\"color: #05013c; text-align: justify;\">Common Market for Eastern and Southern Africa ou M<\/em><em style=\"color: #05013c; text-align: justify;\">arch\u00e9 commun pour l\u2019Afrique de l\u2019Est et du Sud,<\/em><span style=\"color: #05013c; text-align: justify;\">\u00a0est \u00ab d\u2019\u00eatre\u00a0<\/span><em style=\"color: #05013c; text-align: justify;\">une communaut\u00e9 \u00e9conomique r\u00e9gionale enti\u00e8rement int\u00e9gr\u00e9e, internationalement comp\u00e9titive avec des hauts niveaux de vie de son peuple pr\u00eat \u00e0 fusionner en une Communaut\u00e9 \u00e9conomique africaine<\/em><span style=\"color: #05013c; text-align: justify;\">\u00a0\u00bb<\/span><\/p><\/div><\/div><\/div><\/div><div class=\"x-section e6314-e13 m4ve-0\"><div class=\"x-container max width e6314-e14 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e15 m4ve-4\"><hr class=\"x-line e6314-e16 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e17 m4ve-7\"><p style=\"text-align: justify;\">Le<span>\u00a0<\/span><a href=\"https:\/\/varietycatalogue.comesa.int\/web\/varietycatalogue\" target=\"_blank\" rel=\"noopener\">COMESA Variety Catalogue<\/a><span>\u00a0<\/span>affiche la liste des semences produites par les firmes capitalistes DuPont, Monsanto, Syngenta, etc. plut\u00f4t connues pour soutenir l\u2019agriculture industrielle.<\/p>\n<p style=\"text-align: justify;\"><strong>La vision de l\u2019Union africaine pour l\u2019agriculture est que d\u2019ici \u00e0 2015, le continent devrait :<\/strong><\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li>Am\u00e9liorer la productivit\u00e9 de l\u2019agriculture pour atteindre un taux annuel moyen de croissance de la production de 6%, avec une attention particuli\u00e8re aux petits agriculteurs, en particulier les femmes;<\/li>\n \t<li>Avoir des march\u00e9s agricoles dynamiques au sein des pays et entre les r\u00e9gions;<\/li>\n \t<li>Avoir int\u00e9gr\u00e9 les agriculteurs dans l\u2019\u00e9conomie de march\u00e9, avoir un meilleur acc\u00e8s aux march\u00e9s pour devenir un exportateur net de produits agricoles prenant en compte l\u2019avantage comparatif et comp\u00e9titif de l\u2019Afrique<\/li>\n \t<li>\u2026<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>\u00ab\u00a0On\u00a0\u00bb en est loin\u00a0!<\/strong><\/span><\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li>La RDC est membre du<span>\u00a0<\/span><a href=\"https:\/\/www.uneca.org\/oria\/pages\/comesa-common-market-eastern-and-southern-africa\" target=\"_blank\" rel=\"noopener\">COMESA<\/a><\/li>\n \t<li>Le COMESA pour l\u2019agriculture accorderait une attention particuli\u00e8re aux petits agriculteurs, en particulier aux femmes.\u00a0A voir le<span>\u00a0<\/span><a href=\"http:\/\/thierryregards.eu\/en\/2015\/11\/rdc-agriculture-budget-une-mascarade\/\" target=\"_blank\" rel=\"noopener\">budget de la RDC 2016<\/a>, il n\u2019est pas \u00e9vident d\u2019y voir l\u2019attention particuli\u00e8re du gouvernement Matata sous l\u2019\u00e9gide du Pr\u00e9sident Kabila \u00e0 l\u2019agriculture familiale et aux femmes pr\u00e9conis\u00e9e par le COMESA\u00a0! Au contraire, la RDC s\u2019engage dans l\u2019autre volet du d\u00e9veloppement agricole pr\u00f4n\u00e9 par le COMESA, la cr\u00e9ation de l\u2019\u00e9conomie de march\u00e9 et donc le renforcement de l\u2019agrobusiness ayant comme cons\u00e9quence, la d\u00e9pendance alimentaire\u2026<\/li>\n \t<li>Le volet agriculture du COMESA est financ\u00e9 entre autres par l\u2019USAID\u2026 L\u2019USAID n\u2019est pas vraiment le partenaire id\u00e9al pour la promotion de l\u2019agriculture familiale de petites tailles et pour le d\u00e9veloppement local avec une approche \u00e9cologique\u00a0!<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Il est donc facile \u00e0 comprendre que la politique du Pr\u00e9sident Kabila men\u00e9e par son Premier Ministre est tout sauf \u00ab\u00a0agriculture familiale ET \u00e9cologique\u00a0\u00bb\u00a0!<\/strong><\/p><\/div><div class=\"x-text x-content e6314-e18 m4ve-7\"><h1><span style=\"color: #800000; font-size: 42px;\">Accaparement des graines de l'Afrique<\/span><\/h1><\/div><\/div><\/div><div class=\"x-container max width e6314-e19 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-5 e6314-e20 m4ve-4 m4ve-5\"><span class=\"x-image e6314-e21 m4ve-c\"><img decoding=\"async\" src=\"https:\/\/www.thierryregards.eu\/wp-content\/uploads\/2015\/12\/ACB.png\" width=\"157\" height=\"150\" alt=\"Image\" loading=\"lazy\"><\/span><\/div><div class=\"x-column x-sm x-4-5 e6314-e22 m4ve-4\"><hr class=\"x-line e6314-e23 m4ve-9 m4ve-a\"\/><div class=\"x-text x-content e6314-e24 m4ve-7\"><p style=\"text-align: justify;\"><strong style=\"color: #05013c;\">USAID, l&rsquo;UE et la Fondation Gates soutiennent la prise de contr&ocirc;le des semences via le COMESA &ndash; March&eacute; commun pour l&rsquo;Afrique de l&rsquo;Est et du Sud&hellip;&nbsp;<\/strong><a href=\"https:\/\/acbio.org.za\/en\/grabbing-africas-seeds-usaid-eu-and-gates-foundation-back-agribusiness-seed-takeover\" target=\"_blank\" rel=\"noopener\">ACB Grabbing Africa&rsquo;s seeds: USAID, EU and Gates Foundation back agribusiness seed takeover&hellip;<\/a><\/p><\/div><\/div><\/div><\/div><div class=\"x-section e6314-e25 m4ve-0\"><div class=\"x-container max width e6314-e26 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e27 m4ve-4\"><hr class=\"x-line e6314-e28 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e29 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>12 mai 2015.&nbsp;<\/strong>La derni&egrave;re salve dans la bataille sur les syst&egrave;mes de semences de l&rsquo;Afrique a &eacute;t&eacute; tir&eacute;e avec la Fondation Gates et l&rsquo;USAID jouant avec les marionnettes des gouvernements africains, pour faire avancer les r&eacute;glementations sur les semences favorables aux entreprises de l&rsquo;agrobusiness avec comme cons&eacute;quence l&rsquo;exclusion et la marginalisation des petits agriculteurs dont les graines et la main d&rsquo;&oelig;uvre nourrissent le continent.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Plus de 80% de l&rsquo;approvisionnement en semences de l&rsquo;Afrique provient actuellement de millions de petits agriculteurs qui recyclent et &eacute;changent leurs graines d&rsquo;ann&eacute;e en ann&eacute;e.<\/strong>&nbsp;Ces semences r&eacute;pondent &agrave; des besoins tr&egrave;s vari&eacute;s dans des conditions tr&egrave;s diverses.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Addis Abeba, 22 mars 2015&nbsp;<\/strong>Une r&eacute;union sur la biotechnologie et la bios&eacute;curit&eacute; a &eacute;t&eacute; tenue pour &eacute;tablir un &laquo;&nbsp; Plan de mise en &oelig;uvre de la politique en mati&egrave;re de biotechnologie et bios&eacute;curit&eacute; du COMESA&nbsp;(COMBIP)&raquo; &agrave; d&eacute;ployer entre 2015-2019, &laquo;&nbsp;conduisant &agrave; une augmentation des applications de biotechnologiques et de commerce des produits agricoles dans la r&eacute;gion.&nbsp;&raquo;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Mais &agrave; lire entre les lignes, son v&eacute;ritable objectif &eacute;tait de faciliter la plantation et la commercialisation des cultures d&rsquo;OGM en Afrique en un seul coup, au lieu de le faire pays par pays. Les repr&eacute;sentants r&eacute;gionaux de l&rsquo;USAID pour l&rsquo;Afrique de l&rsquo;Est, bas&eacute; &agrave; Nairobi, &eacute;taient pr&eacute;sents pour surveiller le processus et garantir le r&eacute;sultat souhait&eacute;.&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Et &agrave; l&rsquo;ordre du jour pour le Sommet du COMESA la semaine suivante est l&rsquo;approbation &laquo;&nbsp;d&rsquo;un Plan directeur&nbsp;&raquo; pour la mise en &oelig;uvre du&nbsp;<\/span><a href=\"https:\/\/varietycatalogue.comesa.int\/web\/downloadfile\/documents%252Fregional%252FCOMESA%2520Seed%2520Trade%2520Harmonisation%2520Regulations%2520French.pdf\" target=\"_blank\" rel=\"noopener\">COMESA des R&egrave;glements de Commerce de Graine Harmonis&eacute;s PDF<\/a><span style=\"color: #05013c;\">, accept&eacute;s l&rsquo;ann&eacute;e derni&egrave;re (2014) &agrave; Kinshasa.&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><span style=\"color: #800000;\"><strong>Pas de place pour les petits agriculteurs !<\/strong>&nbsp;<\/span>Ce qui est tr&egrave;s clair, c&rsquo;est que les petits agriculteurs en Afrique, cherchant &agrave; d&eacute;velopper ou maintenir des vari&eacute;t&eacute;s, de cr&eacute;er des entreprises de semences locales ou de cultiver des vari&eacute;t&eacute;s localement adapt&eacute;es sont exclus du syst&egrave;me de certification des semences propos&eacute; par COMESA et le Syst&egrave;me d&rsquo;homologation des vari&eacute;t&eacute;s, parce que ces vari&eacute;t&eacute;s ne correspondent pas aux exigences de distinction, d&rsquo;homog&eacute;n&eacute;it&eacute; et de stabilit&eacute; (DHS) &ndash; distinctness, uniformity and stability (DUS)<em>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Les vari&eacute;t&eacute;s traditionnelles ou les vari&eacute;t&eacute;s des agriculteurs affichent g&eacute;n&eacute;ralement un degr&eacute; &eacute;lev&eacute; d&rsquo;h&eacute;t&eacute;rog&eacute;n&eacute;it&eacute; g&eacute;n&eacute;tique et sont adapt&eacute;s &agrave; l&rsquo;environnement local en vertu de laquelle ils ont &eacute;t&eacute; d&eacute;velopp&eacute;s. En outre, ces vari&eacute;t&eacute;s ne sont pas n&eacute;cessairement distinctes les unes des autres.&nbsp;<\/span><a href=\"https:\/\/www.alternet.org\/2015\/03\/how-gates-foundation-and-western-countries-are-plotting-take-control-africas-agriculture\/\" target=\"_blank\" rel=\"noopener\">AlterNet<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Le contr&ocirc;le des semences en Europe et dans le Monde par les grandes soci&eacute;t&eacute;s de l&rsquo;agrobusiness existent d&eacute;j&agrave;,&nbsp;<\/strong>affaiblissant d&rsquo;autant la diversit&eacute; naturelle des ressources alimentaires au profit du business, de l&rsquo;argent, du pouvoir &eacute;conomique au d&eacute;triment de l&rsquo;Humain dans sa diversit&eacute; et globalit&eacute;. L&rsquo;organisation en charge de cela est l&rsquo;<\/span><a href=\"http:\/\/www.upov.int\/portal\/index.html.fr\" target=\"_blank\" rel=\"noopener\">Union internationale pour la protection des obtentions v&eacute;g&eacute;tales (UPOV)<\/a><span style=\"color: #05013c;\">&nbsp;est une organisation intergouvernementale ayant son si&egrave;ge &agrave; Gen&egrave;ve (Suisse). Elle a pour but la protection des brevets et donc des droits acquis par ces entreprises, sur un bien, la nourriture, qui devrait &ecirc;tre libre et non la propri&eacute;t&eacute; que quelques puissances.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>La&nbsp;<\/em><\/span><a href=\"http:\/\/www.upov.int\/upovlex\/fr\/upov_convention.html\" target=\"_blank\" rel=\"noopener\">Convention UPOV<\/a><span style=\"color: #05013c;\"><em>instaure un syst&egrave;me&nbsp;sui generis&nbsp;<\/em>(sui generis = sp&eacute;cifique et unique de son esp&egrave;ce)<em>&nbsp;de protection de la propri&eacute;t&eacute; intellectuelle qui est sp&eacute;cialement adapt&eacute; au processus d&rsquo;am&eacute;lioration des plantes et vise &agrave; encourager les obtenteurs &agrave; cr&eacute;er de nouvelles vari&eacute;t&eacute;s de plantes.<\/em>&nbsp;Comprenez, obtenteurs, les soci&eacute;t&eacute;s capables de payer la recherche et en faire un brevet ce dont la majorit&eacute; des agriculteurs du Monde en sont incapables, et de facto en deviennent leurs esclaves &eacute;conomiques.<strong>&nbsp;Site &agrave; d&eacute;couvrir&nbsp;<\/strong><\/span><a href=\"https:\/\/www.semencespaysannes.org\/\" target=\"_blank\" rel=\"noopener\">Semences paysannes<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.grain.org\/article\/entries\/683-seed-aid-agribusiness-and-the-food-crisis\" target=\"_blank\" rel=\"noopener\">www.grain.org<\/a><span style=\"color: #05013c;\">&nbsp;&agrave; propos des slogans de l&rsquo;agrobusiness :&nbsp;<strong>Polarisation de possibilit&eacute;s de d&eacute;veloppement de l&rsquo;agriculture.&nbsp;<\/strong><em>&Agrave; tous les niveaux, des minist&egrave;res de l&rsquo;agriculture &agrave; la Banque mondiale, l&rsquo;enjeu de fond, le contr&ocirc;le de l&rsquo;alimentation, est masqu&eacute;e par un discours ignorant la r&eacute;alit&eacute; :<\/em><\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"color: #05013c;\"><em>Les agriculteurs ne disposent pas de semences, les &laquo; bonnes semences&nbsp;&raquo; ;<\/em><\/span><\/li>\n<li><span style=\"color: #05013c;\"><em>Pour fournir les &laquo;&nbsp;bonnes&nbsp;&raquo; semences aux agriculteurs, les gouvernements doivent adopter les structures de march&eacute; appropri&eacute;es, y compris des syst&egrave;mes de certification des semences, des r&egrave;gles souples de pr&eacute;vention des risques biotechnologiques et des r&eacute;gimes de propri&eacute;t&eacute; intellectuelle.<\/em><em>&nbsp;<\/em><\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><span style=\"color: #800000;\"><strong>Zones d&rsquo;ombre<\/strong><\/span>&nbsp;D&rsquo;o&ugrave; viennent ces affirmations par lesquelles les agriculteurs ne disposeraient pas de bonnes semences, d&rsquo;aucunes &laquo;&nbsp;bonnes semences&nbsp;&raquo;&nbsp;? Que veut dire &laquo;&nbsp;bonnes&nbsp;&raquo; semences&nbsp;? D&rsquo;o&ugrave; vient ce slogan par lequel la seule voie du d&eacute;veloppement est &laquo;&nbsp;le march&eacute;&nbsp;&raquo; alors que l&rsquo;&eacute;conomie mondiale s&rsquo;auto d&eacute;truit gr&acirc;ce &agrave; ce fameux march&eacute;&nbsp;? Qu&rsquo;est-ce qui&nbsp; se cache derri&egrave;re ces affirmations pos&eacute;es comme absolues&nbsp;? Au service de qui&nbsp;?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em><strong>L&rsquo;accent mis sur la sup&eacute;riorit&eacute; de &laquo;&nbsp;bonnes&nbsp;semences &raquo; est un quasi eug&eacute;nisme<\/strong>&nbsp;<\/em>(mot &agrave; comprendre comme la s&eacute;lection et reproduction des individus dont le potentiel g&eacute;n&eacute;tique est le plus &eacute;lev&eacute; et suppression de tout autre sp&eacute;cimen d&eacute;truisant ainsi la biodiversit&eacute;<em>).&nbsp;<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em><strong>Pour l&rsquo;agrobusiness, les &laquo;&nbsp;bonnes&nbsp;&raquo; semences sont les hybrides, les OGM (Organisme G&eacute;n&eacute;tiquement Modifi&eacute;), les vari&eacute;t&eacute;s certifi&eacute;es ou am&eacute;lior&eacute;es<\/strong>, lesquels sont &laquo;&nbsp;les seuls&nbsp;&raquo; &agrave; donner des rendements &eacute;lev&eacute;s et sont donc &laquo;&nbsp;la seule&nbsp;&raquo; fa&ccedil;on de sortir de la crise alimentaire.&nbsp;<strong>Les &laquo;&nbsp;mauvaises&nbsp;&raquo; graines ou graines &laquo;&nbsp;d&eacute;fectueuses&nbsp;&raquo; sont pour les leaders de l&rsquo;agrobusiness, les semences paysannes, les graines non certifi&eacute;es, les vari&eacute;t&eacute;s paysannes, en fait tout ce qui n&rsquo;est pas pass&eacute; par un laboratoire de recherches et qui n&rsquo;a pas re&ccedil;u une approbation gouvernementale.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>En fin du compte, la r&eacute;ponse &agrave; la crise alimentaire mondiale ayant pour slogan &laquo;&nbsp;Nous devons stimuler la production!&nbsp;&raquo; loin d&rsquo;un d&eacute;bat politique approfondi conduit &agrave; des r&eacute;ponses r&eacute;flexes, comme celles o&ugrave; les &nbsp;grandes puissances agro industrielles versent des milliards de dollars dans la distribution de nouvelles graines, les &laquo;&nbsp;semences am&eacute;lior&eacute;es&nbsp;&raquo; &agrave; des centaines de millions de petits cultivateurs.&nbsp;<strong>Ces r&eacute;ponses permettent aux capitaux priv&eacute;s, y compris aux investissements purement sp&eacute;culatifs, de prendre le contr&ocirc;le de ce qui est habituellement appel&eacute; le d&eacute;veloppement agricole et de le transformer &laquo;&nbsp;tout simplement&nbsp;&raquo; en d&eacute;veloppement de l&rsquo;agrobusiness !&nbsp;<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em><strong><span style=\"color: #800000;\">Il est clair qu&rsquo;&agrave; moins de voir cette invasion arr&ecirc;t&eacute;e, les b&eacute;n&eacute;ficiaires suppos&eacute;s, les petits cultivateurs en seront les victimes.<\/span>&nbsp;<\/strong><\/em><\/span><a href=\"https:\/\/www.grain.org\/article\/entries\/683-seed-aid-agribusiness-and-the-food-crisis\" target=\"_blank\" rel=\"noopener\">grain.org Seed aid, agribusiness and the food crisis<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Il faut dire que ces entreprises soutenues par des fondations et des organisations internationales, des banques, des gouvernements vendus au capitalisme casino, disposent d&rsquo;&eacute;normes moyens de propagande et de lobbying, &agrave; l&rsquo;image du Trait&eacute; Transatlantique&nbsp;pour l&rsquo;Investissement et le Partenariat entre les USA et l&rsquo;UE.&nbsp;<strong>Lire article sur le&nbsp;<\/strong><\/span><a href=\"http:\/\/thierryregards.eu\/en\/2014\/12\/tournai-dit-non-au-ttip\/\" target=\"_blank\" rel=\"noopener\">TTIP \/ CETA<\/a><span style=\"color: #05013c;\"><strong>&nbsp;et&nbsp;<\/strong><\/span><a href=\"http:\/\/thierryregards.eu\/en\/2015\/06\/rdc-larnaque-des-pais-le-mais-nourriture-ou-produit-financier\/\" target=\"_blank\" rel=\"noopener\">Le ma&iuml;s, nourriture ou produit financier ?<\/a><\/p><\/div><\/div><\/div><\/div><div class=\"x-section e6314-e30 m4ve-0\"><div class=\"x-container max width e6314-e31 m4ve-1 m4ve-3\"><div class=\"x-column x-sm x-1-1 e6314-e32 m4ve-4 m4ve-6\"><hr class=\"x-line e6314-e33 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e34 m4ve-7\"><div id=\"x-content-band-2\" class=\"x-content-band bg-image parallax border-top border-left border-right border-bottom\" data-x-element=\"content_band\" data-x-params=\"{&quot;type&quot;:&quot;image&quot;,&quot;parallax&quot;:true}\" style=\"background-image: url(http:\/\/thierryregards.eu\/wp-content\/uploads\/2015\/06\/060212-104.jpg); background-color: transparent; color: #fff;font-size:32px\"><div class=\"x-container max width\">Pour comprendre les enjeux de l\u2019agriculture en RDC, il est int\u00e9ressant de voir ce qui est r\u00e9alis\u00e9 aux USA dont l\u2019USAID, la Fondation Bill Gates et bien d\u2019autres organisations am\u00e9ricaines sont les promoteurs \u00e0 l\u2019\u00e9tranger.<\/div><\/div><\/div><div class=\"x-text x-content e6314-e35 m4ve-7\"><h1><span style=\"color: #800000; font-size: 42px;\">Les agro-industriels aux Etats-Unis\u00a0<\/span><\/h1><\/div><\/div><\/div><div class=\"x-container max width e6314-e36 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-3 e6314-e37 m4ve-4\"><span class=\"x-image e6314-e38 m4ve-c\"><img decoding=\"async\" src=\"https:\/\/www.thierryregards.eu\/wp-content\/uploads\/2015\/11\/GMA-Members-Boycott-list.jpg\" width=\"425\" height=\"1525\" alt=\"Image\" loading=\"lazy\"><\/span><\/div><div class=\"x-column x-sm x-2-3 e6314-e39 m4ve-4\"><div class=\"x-text x-content e6314-e40 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Selon la GMA \u2013\u00a0<\/span><a href=\"http:\/\/www.gmaonline.org\/\" target=\"_blank\" rel=\"noopener\">Grocery Manufacturers Association<\/a><span style=\"color: #05013c;\">, aux USA :\u00a0<em>\u00ab\u00a0L\u2019industrie de l\u2019alimentaire (aliments, boissons et produits emball\u00e9s) de 2,1 milliards de milliards $ emploie 14 millions de travailleurs am\u00e9ricains, et contribue pour plus de $ 1 billion de dollars en valeur ajout\u00e9e \u00e0 l\u2019\u00e9conomie des Etats-Unis.\u00a0\u00bb\u00a0<\/em>\u00a0<strong>Vous avez lu : 2,1 milliards de milliards de dollars !\u00a0<\/strong>A quoi devrait s\u2019ajouter l\u2019\u00e9conomie de la fabrication de machines agricoles, de la p\u00e9trochimie, des NTIC li\u00e9es \u00e0 l\u2019agro-industrie.\u00a0<strong>Un enjeu financier consid\u00e9rable\u2026<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>La GMA est la plus grande association professionnelle de l\u2019industrie alimentaire aux USA. Parmi ses plus de 300 membres : Pepsi, Coca, Kellogg, Nestl\u00e9, Procter &amp; Gamble, Monsanto\u2026 etc.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">En juin 2014, 4 associations professionnelles, dont GMA intenten<\/span>t<span>\u00a0<\/span><a href=\"http:\/\/www.burlingtonfreepress.com\/story\/news\/politics\/2014\/06\/12\/gma-sues-vt-gmo-law\/10389209\/\" target=\"_blank\" rel=\"noopener\">une action en justice<\/a><span>\u00a0<\/span><span style=\"color: #05013c;\">faite contre l\u2019Etat du Vermont, un \u00e9tat rural de 600.000 habitants\u00a0: son \u00ab\u00a0crime\u00a0\u00bb avoir vot\u00e9 une loi obligeant les producteurs \u00e0 indiquer si leur produit contient des OGM ou non et qui interdit de consid\u00e9rer les OGM comme des produits \u00ab\u00a0naturels\u00a0\u00bb, pratique en cours sur les \u00e9tiquettes de ces soci\u00e9t\u00e9s\u2026 Starbucks et Monsanto, membres de GMA mis en cause par une association\u00a0<\/span><a href=\"http:\/\/action.sumofus.org\/a\/starbucks-gmo-gma\/?sub=homepage\" target=\"_blank\" rel=\"noopener\">SumOfUs<\/a><span style=\"color: #05013c;\"><strong>,<\/strong>\u00a0d\u00e9nient toute participation \u00e0 cette action en justice\u00a0! Mais je n\u2019ai pas lu qu\u2019elle \u00e9tait leur position sur l\u2019action en justice\u00a0de GMA comme pour dire le c\u0153ur sur la main\u00a0: \u00ab\u00a0<em>Vous savez nous, on y est pour rien, on est seulement membre mais pas responsable\u2026<\/em>\u00bb<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>C\u2019est effarent de na\u00efvet\u00e9 de leur part de penser me faire croire \u00ab\u00a0<em>qu\u2019elles sont des victimes innocentes<\/em>\u00a0\u00bb d\u2019une nouvelle chasse aux sorci\u00e8res en leur attribuant d\u2019office tous les maux !<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Si vous allez sur le site de GMA, vous trouverez toutes sortes d\u2019information sur leur implication dans la promotion du d\u00e9veloppement durable\u00a0allant jusqu\u2019\u00e0 vanter leur contribution \u00e0 l\u2019\u00e9conomie am\u00e9ricaine !<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">C\u2019est curieux parce qu\u2019en mars 2010 d\u00e9j\u00e0, Mich\u00e8le Obama, \u00e9pouse du Pr\u00e9sident des Etats-Unis d\u2019Am\u00e9rique exhortait la GMA de prendre en compte le probl\u00e8me de l\u2019ob\u00e9sit\u00e9 des enfants am\u00e9ricains due aux produits hautement sucr\u00e9s sal\u00e9s de leur junkfood\u00a0(malbouffe) ! Lisez sa d\u00e9claration, c\u2019est \u00e9difiant. Si c\u2019est \u00e7\u00e0 contribuer \u00e0 la richesse du pays, non merci\u00a0! Et les USA se disent \u00ab\u00a0pays d\u00e9velopp\u00e9\u00a0\u00bb, cherchez l\u2019erreur\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/obamawhitehouse.archives.gov\/the-press-office\/remarks-first-lady-a-grocery-manufacturers-association-conference\" target=\"_blank\" rel=\"noopener\">Remarks by the First Lady at a Grocery Manufacturers Association Conference<\/a><\/p><\/div><\/div><\/div><\/div><div class=\"x-section e6314-e41 m4ve-0\"><div class=\"x-container max width e6314-e42 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e43 m4ve-4\"><hr class=\"x-line e6314-e44 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e45 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Et donc le projet du Pr\u00e9sident Kabila, celui de la \u00ab\u00a0R\u00e9volution de la modernit\u00e9\u00a0\u00bb est d\u2019offrir de la malbouffe au plus grand nombre de ses concitoyens. Au moins ils ne mourront plus de faim\u00a0<\/strong><strong>mais de surpoids, de cancers, d\u2019allergies, etc. \u00e0 l\u2019exemple de ce qui existe d\u00e9j\u00e0 dans les pays \u00ab\u00a0d\u00e9velopp\u00e9s\u00a0\u00bb !\u00a0<\/strong><strong>\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Il n\u2019est pas \u00e9tonnant de retrouver ces entreprises en Afrique, et particuli\u00e8rement en RDC dont le gouvernement est favorable \u00e0 l\u2019exploitation de ses 80 millions d\u2019hectares de terres arables dont \u00ab\u00a0seulement\u00a0\u00bb 10 % sont exploit\u00e9s\u00a0!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>A des conditions d\u00e9fiant toute concurrence :<\/strong>\u00a0La r\u00e9ussite du projet Partenariat Public Priv\u00e9 repose sur l\u2019attractivit\u00e9 \u00e9conomique du projet industriel sur le plan des avantages et facilit\u00e9s accord\u00e9es, offertes par l\u2019Etat.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #05013c;\">Les i<\/span><span><span style=\"color: #05013c;\">ncitations fiscales et douani\u00e8res \u00e0 d\u00e9couvrir sur<\/span>\u00a0<\/span><\/strong><a href=\"http:\/\/thierryregards.eu\/en\/2015\/03\/rdc-plan-national-investissement-agriculture-pnia\/\" target=\"_blank\" rel=\"noopener\">RDC \u2013 Plan National d\u2019Investissement Agricole-PNIA<\/a><\/p><\/div><\/div><\/div><\/div><div class=\"x-section e6314-e46 m4ve-0\"><div class=\"x-container max width e6314-e47 m4ve-1 m4ve-3\"><div class=\"x-column x-sm x-1-1 e6314-e48 m4ve-4 m4ve-6\"><div class=\"x-text x-content e6314-e49 m4ve-7\"><h1><span style=\"color: #800000; font-size: 42px;\">Les divulgateurs\u00a0<\/span><\/h1><\/div><\/div><\/div><div class=\"x-container max width e6314-e50 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-5 e6314-e51 m4ve-4 m4ve-5\"><span class=\"x-image e6314-e52 m4ve-c\"><img decoding=\"async\" src=\"https:\/\/www.thierryregards.eu\/wp-content\/uploads\/2015\/03\/IITA.jpg\" width=\"194\" height=\"60\" alt=\"Image\" loading=\"lazy\"><\/span><\/div><div class=\"x-column x-sm x-4-5 e6314-e53 m4ve-4\"><div class=\"x-text x-content e6314-e54 m4ve-7\"><p style=\"text-align: justify;\"><a href=\"https:\/\/www.iita.org\/\" target=\"_blank\" rel=\"noopener\">IITA\u00a0\u2013\u00a0The\u00a0International Institute of Tropical Agriculture<\/a>\u00a0<span style=\"color: #05013c;\">dont une antenne est\u00a0install\u00e9e \u00e0 Bukavu, est financ\u00e9 entre autre par\u00a0:<\/span><strong><\/strong><\/p><\/div><\/div><\/div><div class=\"x-container max width e6314-e55 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e56 m4ve-4\"><hr class=\"x-line e6314-e57 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e58 m4ve-7\"><ul>\n \t<li style=\"text-align: justify;\"><a href=\"http:\/\/www.gatesfoundation.org\/\" target=\"_blank\" rel=\"noopener\">Bill &amp; Melinda Gates Foundatio<\/a><span style=\"color: #05013c;\"><a href=\"http:\/\/www.gatesfoundation.org\/\" target=\"_blank\" rel=\"noopener\" style=\"color: #05013c;\">n<\/a>, fondation largement critiqu\u00e9e pour son implication dans la promotion des semences OGM via Monsanto, une des Cie les plus d\u00e9test\u00e9es au Monde !\u00a0<\/span><a href=\"http:\/\/trends.levif.be\/economie\/entreprises\/et-les-13-societes-les-plus-detestees-du-monde-sont\/article-normal-195545.html\" target=\"_blank\" rel=\"noopener\">Trends \u2013 13 soci\u00e9t\u00e9s les plus d\u00e9test\u00e9es dans le monde<\/a><span style=\"color: #05013c;\">,\u00a0&amp;\u00a0<\/span><a href=\"https:\/\/acbio.org.za\/en\" target=\"_blank\" rel=\"noopener\">African Center for Biodiversity<\/a><span style=\"color: #05013c;\">,<\/span><\/li>\n \t<li style=\"text-align: justify;\"><a href=\"http:\/\/www.usda.gov\/wps\/portal\/usda\/usdahome?navid=ABOUT_USDA\" target=\"_blank\" rel=\"noopener\">USDA \u2013 U.S. Department of Agriculture<\/a><span style=\"color: #05013c;\">\u00a0Ce\u00a0d\u00e9partement subventionne son agriculture am\u00e9ricaine qui d\u00e9pend pour beaucoup de l\u2019exportation dont les produits USAID \u00ab\u00a0og\u00e9emis\u00e9s\u00a0\u00bb<\/span><\/li>\n \t<li style=\"text-align: justify;\"><span style=\"color: #05013c;\">la\u00a0<\/span><a href=\"http:\/\/thierryregards.eu\/en\/2015\/03\/rdc-pais-les-complices-banque-mondiale\/\" target=\"_blank\" rel=\"noopener\">Banque mondiale<\/a><span style=\"color: #05013c;\">\u00a0qui subventionnent ou financent l\u2019agrobusiness et donc les produits OGM.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #05013c;\">Il est clair que la tendance des actions men\u00e9es par l\u2019IITA sera conditionn\u00e9e par ces \u00ab\u00a0partenaires\u00a0\u00bb\u00a0qui en attendent un \u00ab\u00a0retour sur investissement\u00a0\u00bb, la vente de produits OGM et de produits chimiques !\u00a0<\/span><\/strong><\/p><\/div><hr class=\"x-line e6314-e59 m4ve-8 m4ve-9\"\/><\/div><\/div><div class=\"x-container max width e6314-e60 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-5 e6314-e61 m4ve-4 m4ve-5\"><hr class=\"x-line e6314-e62 m4ve-9 m4ve-b\"\/><span class=\"x-image e6314-e63 m4ve-c\"><img decoding=\"async\" src=\"https:\/\/www.thierryregards.eu\/wp-content\/uploads\/2015\/12\/HarvestPlus.jpg\" width=\"150\" height=\"132\" alt=\"Image\" loading=\"lazy\"><\/span><\/div><div class=\"x-column x-sm x-4-5 e6314-e64 m4ve-4\"><div class=\"x-text x-content e6314-e65 m4ve-7\"><p style=\"text-align: justify;\"><a href=\"https:\/\/www.harvestplus.org\/\" target=\"_blank\" rel=\"noopener\">HarvestPlus<\/a><strong><em>\u00a0 <span style=\"color: #05013c;\">Notre vision.\u00a0<\/span><\/em><\/strong><span style=\"color: #05013c;\"><em>HarvestPlus a pour objectif de r\u00e9duire les carences en micronutriments en augmentant leur teneur dans les aliments de base consomm\u00e9s \u00e0 chaque repas par des milliards de personnes. HarvestPlus emploie la biofortification, une approche nouvelle consistant \u00e0 augmenter la teneur en micronutriments directement dans les cultures de subsistance dont se nourrissent les populations pauvres. \u2026<\/em><\/span><\/p><\/div><\/div><\/div><div class=\"x-container max width e6314-e66 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e67 m4ve-4\"><hr class=\"x-line e6314-e68 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e69 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>HarvestPlus est une alliance mondiale compos\u00e9e d\u2019instituts de recherche et d\u2019organismes de mise en \u0153uvre qui travaillent ensemble afin d\u2019am\u00e9liorer et de diss\u00e9miner les cultures pour une meilleure alimentation.<\/em><em>\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>La coordination est assur\u00e9e par le Centre international d\u2019agriculture tropicale (<\/em><\/span><a href=\"https:\/\/ciat.cgiar.org\/\" target=\"_blank\" rel=\"noopener\">CIAT<\/a><span style=\"color: #05013c;\"><em>) et par l\u2019Institut international de recherche sur les politiques alimentaires (<\/em><\/span><a href=\"http:\/\/www.ifpri.org\/\" target=\"_blank\" rel=\"noopener\">IFPRI<\/a><span style=\"color: #05013c;\"><em>).\u00a0HarvestPlus est une initiative du Groupe consultatif pour la recherche agricole internationale (<\/em><\/span><a href=\"http:\/\/www.cgiar.org\/\" target=\"_blank\" rel=\"noopener\">CGIAR<\/a><span style=\"color: #05013c;\"><em>), une alliance au niveau mondial qui mobilise la science pour aider les populations pauvres.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>15 d\u00e9cembre 2015.<\/strong>\u00a0Infos Grands Lacs et Radio Okapi ont r\u00e9alis\u00e9 chacun de leur c\u00f4t\u00e9 un reportage sur HarvestPlus avec comme titre respectif\u00a0:\u00a0<\/span><a href=\"http:\/\/infosgrandslacs.info\/productions\/bukavu-long-harvest-plus-associe-les-agriculteurs-dans-le-choix-des-semences\" target=\"_blank\" rel=\"noopener\">Bukavu : l\u2019ONG Harvest Plus associe les agriculteurs dans le choix des semences<\/a> et\u00a0\u00a0<a href=\"http:\/\/www.radiookapi.net\/regions\/nord-kivu\/2015\/01\/09\/vulgarisation-des-semences-fortifiees-aupres-des-paysans-de-goma\" target=\"_blank\" rel=\"noopener\">Vulgarisation des semences fortifi\u00e9es aupr\u00e8s des paysans de Goma<\/a><span style=\"color: #05013c;\">. Un classique du genre journalistique qui relate un \u00e9v\u00e9nement sans esprit critique sur les enjeux qui vont au-del\u00e0 de ce qui est pr\u00e9sent\u00e9 par le commanditaire de l\u2019article.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong><span style=\"color: #800000;\">Zones d\u2019ombre<\/span>\u00a0<\/strong>Il est dit qu\u2019avec les vari\u00e9t\u00e9s test\u00e9es \u00e0 l\u2019INERA Sud-Kivu \u2013 Mulungu, il sera possible d\u2019effectuer\u00a0<strong>2 r\u00e9coltes de ma\u00efs par an,<\/strong>comme pour le haricot,\u00a0<strong>avec une semence adapt\u00e9e au changement climatique.<\/strong>\u00a0Un agriculteur appr\u00e9cie le fait qu\u2019avec les\u00a0<strong>semences hybrides donn\u00e9es par HarvestPlus<\/strong>, il produit d\u00e9j\u00e0 plus de 5 tonnes\/ha au lieu d\u2019une et, esp\u00e8re m\u00eame atteindre 8t\/ha\u00a0!<\/span><\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li><span style=\"color: #05013c;\">De quelles semences hybrides et \u00ab\u00a0bio fortifi\u00e9es\u00a0\u00bb s\u2019agit-il\u00a0? Qui les a cr\u00e9\u00e9es\u00a0? D\u2019o\u00f9 proviennent-elles\u00a0? L\u2019INERA ne communique aucune information sur ce projet. Quels ont \u00e9t\u00e9 les recherches faites sur place\u00a0?<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">Que veut dire \u00ab\u00a0associer\u00a0les agriculteurs\u00a0\u00bb\u00a0? Associer \u00e0 quoi exactement\u00a0?<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">Semences donn\u00e9es par HarvestPlus ou par INERA\u00a0? Ces semences \u00ab\u00a0gratuites\u00a0\u00bb le sont-elles r\u00e9ellement puisque les producteurs sont oblig\u00e9s de \u00ab\u00a0rembourser\u00a0\u00bb en nature lors de la r\u00e9colte\u2026\u00a0?<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">Ces semences sont sous licence gratuite, ok sont-elles \u00e0 usage unique ce qui obligerait\u00a0 l\u2019agriculteur \u00e0 en acheter \u00e0 l\u2019avenir\u00a0? Peut-il rester autonome en r\u00e9utilisant ses propres graines\u00a0?<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">Il n\u2019est pas expliqu\u00e9 comment le sol pauvre du Sud-Kivu sera fertilis\u00e9 \u00e0 la suite d\u2019une telle surexploitation \u2026<\/span><\/li>\n \t<li><span style=\"color: #05013c;\"><em>\u00ab\u00a0La biofortification, une approche nouvelle\u00a0\u00bb<\/em>, en quoi est-elle vraiment nouvelle\u00a0? Elle existe depuis toujours !<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">HarvestPlus d<span style=\"color: #05013c;\">onne de l\u2019information sur son site web via sa page <\/span><a href=\"https:\/\/www.harvestplus.org\/about\/faqs\" target=\"_blank\" rel=\"noopener\">HarvestPlus - FAQ about Biofortification<\/a><span style=\"color: #05013c;\">, mais\u2026<\/span><\/p>\n<p style=\"text-align: justify; padding-left: 60px;\"><span style=\"color: #05013c;\"><strong><em>Will farmers have to buy seeds every year?<\/em><\/strong> <em>Les fermiers doivent-ils acheter les semences chaque ann\u00e9e ?<\/em> <em>De nombreuses cultures, comme la patate douce, le manioc, le mil et les haricots, peuvent \u00eatre replant\u00e9es chaque ann\u00e9e \u00e0 partir de boutures de plantes ou de semences que le producteur a conserv\u00e9es. Dans le cas des hybrides, les agriculteurs ach\u00e8tent g\u00e9n\u00e9ralement des semences fra\u00eeches pour chaque saison de plantation afin de maintenir une productivit\u00e9 \u00e9lev\u00e9e. M\u00eame les agriculteurs \u00e0 faible revenu pr\u00e9f\u00e8rent acheter des semences hybrides en raison de leur rendement plus \u00e9lev\u00e9.<\/em> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">La r\u00e9ponse est subtile pour tromper\u00a0: tout d\u2019un coup il est question de semence \u00ab\u00a0commune\u00a0\u00bb alors que le sujet est l\u2019achat ou non chaque ann\u00e9e de semences biofortifi\u00e9es !\u00a0Curieux non\u00a0?<strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Et il est inform\u00e9 que pour une question de maintenir la haute productivit\u00e9 des r\u00e9coltes, il faut, oui, acheter la semence hybride, chaque ann\u00e9e\u00a0! Mais rassurez-vous, sur le long terme, la diff\u00e9rence de co\u00fbt sera n\u00e9gligeable\u00a0! Il ne s\u2019agit donc pas de permettre aux agriculteurs d\u2019atteindre l\u2019autonomie de production mais de d\u00e9pendre, pieds et mains li\u00e9s par contrat, des producteurs industriels de semences hybrides\u00a0!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Le Pr\u00e9sident Kabila et ses sponsors affirment vouloir la souverainet\u00e9 alimentaire, une alimentation vari\u00e9e, le d\u00e9veloppement durable ? L\u2019arnaque\u00a0!<\/span><\/p>\n<p style=\"text-align: justify; padding-left: 60px;\"><span style=\"color: #05013c;\"><strong><em>Are biofortified crops developed through transgenic modification (GM)? <\/em><\/strong><em>\u00c0 ce jour, toutes les cultures biofortifi\u00e9es lib\u00e9r\u00e9es gr\u00e2ce aux efforts de HarvestPlus et de ses partenaires ont \u00e9t\u00e9 d\u00e9velopp\u00e9es \u00e0 l'aide de la s\u00e9lection v\u00e9g\u00e9tale conventionnelle.<\/em><\/span><em style=\"color: #05013c;\">\u00a0<\/em><\/p>\n<p style=\"text-align: justify; padding-left: 60px;\"><span style=\"color: #05013c;\"><em>HarvestPlus consid\u00e8re que la s\u00e9lection conventionnelle ne rencontre aucun obstacle r\u00e9glementaire et qu'elle est largement accept\u00e9e. Il s'agit donc du moyen le plus rapide pour que les agriculteurs et les consommateurs aient acc\u00e8s \u00e0 des cultures plus nutritives. En outre, seuls quelques pays africains autorisent la modification g\u00e9n\u00e9tique en agriculture. Nous respectons les r\u00e9glementations dans tous les pays o\u00f9 nous travaillons.<\/em>\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Vraiment\u00a0? J\u2019attendais une r\u00e9ponse sans ambigu\u00eft\u00e9 du type\u00a0:<\/strong> la semence biofortifi\u00e9e est obtenue sans manipulation g\u00e9n\u00e9tique ou hybridation de type F1 st\u00e9rile. Elle est stable en qualit\u00e9 et ne n\u00e9cessite pas l\u2019utilisation d\u2019intrants chimiques sp\u00e9cifiques pour son d\u00e9veloppement et sa reproduction. La biofortification soutenue par HarvestPlus exclut toute d\u00e9pendance de l\u2019agriculteur \u00e0 des producteurs de graines puisqu\u2019il peut utiliser librement ses propres graines am\u00e9lior\u00e9es. <strong>Quelque chose comme cela. Ce n\u2019est pas clairement exprim\u00e9 ainsi par HarvestPlus, c\u2019est le moins que l\u2019on puisse dire\u00a0!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>HarvestPlus \u2013 Financements\u00a0<\/strong><\/span><\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li><span style=\"color: #05013c;\">UK Government<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">the Bill &amp; Melinda Gates Foundation<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">the US Government\u2019s Feed the Future initiative<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">the European Commission;<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">Donors to the CGIAR Research Program on Agriculture for Nutrition and Health<\/span><\/li>\n \t<li><span style=\"color: #05013c;\">HarvestPlus is also supported by the John D. and Catherine T. MacArthur Foundation.\u00a0<a href=\"https:\/\/www.harvestplus.org\/about\/our-mission\" style=\"color: #05013c;\">HarvestPlus Our Mission<\/a><\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Le\u00a0greenwashing ou \u00e9coblanchiment est un proc\u00e9d\u00e9 de\u00a0marketing<strong>\u00a0<\/strong>ou de\u00a0relations publiques\u00a0utilis\u00e9 par une organisation (entreprise, administration publique nationale ou territoriale, etc.) dont la caract\u00e9ristique est l\u2019usage d\u2019arguments environnementaux souvent trompeurs dans le but de se donner une image\u00a0\u00e9cologique\u00a0responsable.<em>\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Certains articles posent la question de savoir si finalement, la biofortification ne serait pas le cheval de Troie du contr\u00f4le de l\u2019alimentation par les entreprises priv\u00e9es annihilant de fait, le droit \u00e0 l\u2019alimentation saine, vari\u00e9e et libre pour tous.\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Exemple :\u00a0<\/span><a href=\"http:\/\/www.palgrave-journals.com\/development\/journal\/v57\/n2\/full\/dev201482a.html\" target=\"_blank\" rel=\"noopener\">Biofortification: Trojan horse of corporate food control<\/a><a href=\"http:\/\/www.palgrave-journals.com\/development\/journal\/v57\/n2\/full\/dev201482a.html\" target=\"_blank\" rel=\"noopener\">?<\/a><span style=\"color: #05013c;\"><em>\u00a0La biofortification des cultures de base est consid\u00e9r\u00e9e comme un cheval de Troie pour l\u2019acceptation des aliments g\u00e9n\u00e9tiquement modifi\u00e9s et la poursuite de la consolidation du contr\u00f4le des entreprises sur l\u2019alimentation et l\u2019agriculture. Les programmes publics de biofortification men\u00e9s en utilisant la s\u00e9lection conventionnelle offrent aux entreprises de l\u2019agrobusiness un point d\u2019entr\u00e9e \u00a0dans les cultures vivri\u00e8res de base du Sud. L\u2019accent mis sur les syst\u00e8mes de monoculture qui ont r\u00e9tr\u00e9ci la base di\u00e9t\u00e9tique est la m\u00eame approche que celle adopt\u00e9e pour ramener les micronutriments dans les aliments de base.<\/em><\/span><\/p><\/div><hr class=\"x-line e6314-e70 m4ve-8 m4ve-9\"\/><\/div><\/div><\/div><div class=\"x-section e6314-e71 m4ve-0\"><div class=\"x-container max width e6314-e72 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-5 e6314-e73 m4ve-4 m4ve-5\"><hr class=\"x-line e6314-e74 m4ve-9 m4ve-a\"\/><a class=\"x-image e6314-e75 m4ve-c\" href=\"http:\/\/masipag.org\/about-masipag\/\"><img decoding=\"async\" src=\"https:\/\/www.thierryregards.eu\/wp-content\/uploads\/2015\/12\/MASIPAG-Philippines.png\" width=\"446\" height=\"122\" alt=\"Image\" loading=\"lazy\"><\/a><\/div><div class=\"x-column x-sm x-4-5 e6314-e76 m4ve-4\"><div class=\"x-text x-content e6314-e77 m4ve-7\"><p style=\"text-align: justify;\"><a href=\"http:\/\/masipag.org\/about-masipag\/\">MASIPAG - Philippines<\/a><span style=\"color: #05013c;\">, un r\u00e9seau d\u2019organisations paysannes, d\u2019ONG et de scientifiques travaillant \u00e0 l'utilisation durable et \u00e0 la gestion de biodiversit\u00e9 par le contr\u00f4le de ressources g\u00e9n\u00e9tiques et biologiques par les agriculteurs, de la production agricole et de la connaissance associ\u00e9e, s\u2019inqui\u00e8te aussi de l\u2019utilisation des semences biofortifi\u00e9es comme cheval de Troie des agro-industriels\u00a0:<\/span><\/p><\/div><\/div><\/div><div class=\"x-container max width e6314-e78 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e79 m4ve-4\"><hr class=\"x-line e6314-e80 m4ve-8 m4ve-9\"\/><div class=\"x-text x-content e6314-e81 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>Bien que la Fondation Bill et Melinda Gates soit une organisation philanthropique, son accent est mis sur des solutions de haute technologie tels que l'agriculture chimique et les OGM, donc nous pensons que les projets qu'ils financent ne feront que causer plus de mal parmi les agriculteurs pauvres et les consommateurs \u00bb said Dr. Chito Medina, National Coordinator of MASIPAG.<\/em><em>\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>La Fondation Gates a soutenu des programmes de biofortification alimentaires qui comprend l'enrichissement des cultures de base comme le riz et le manioc. Il soutient \u00e9galement l'Alliance pour une r\u00e9volution verte en Afrique (AGRA) qui est soup\u00e7onn\u00e9 de r\u00e9p\u00e9ter les m\u00eames erreurs de la R\u00e9volution verte en Asie. En 2011, la Fondation Gates a fait don \u00e0 propos de 10,3 millions de dollars pour l'IRRI pour le d\u00e9veloppement du riz dor\u00e9, un riz g\u00e9n\u00e9tiquement modifi\u00e9 qui est pr\u00e9sent\u00e9 pour r\u00e9pondre \u00e0 la carence en vitamine A (CVA) des probl\u00e8mes dans les pays en d\u00e9veloppement, y compris aux Philippines.<\/em><em>\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\"><strong>Lire la suite \u00e9difiante relative au cheval de Troie cit\u00e9 ci-dessus, que sont les semences biofortifi\u00e9es pour le contr\u00f4le de l\u2019agriculture par l\u2019agrobusiness\u00a0: <\/strong><\/span><a href=\"http:\/\/masipag.org\/2015\/04\/farmer-scientist-group-deplore-secretive-visit-of-bill-gates-to-irri-golden-rice-commercialization-possible-agenda\/\" target=\"_blank\" rel=\"noopener\">MASIPAG 150414 Farmer-scientist group deplore secretive visit of Bill Gates to IRRI, Golden Rice commercialization possible agenda<\/a><\/p><\/div><\/div><\/div><\/div><div class=\"x-section e6314-e82 m4ve-0\"><div class=\"x-container max width e6314-e83 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e84 m4ve-4\"><div class=\"x-text x-content e6314-e85 m4ve-7\"><h1><span style=\"color: #800000; font-size: 42px;\">La r\u00e9sistance,\u00a0 le d\u00e9veloppement centr\u00e9 sur la Personne<\/span><\/h1><\/div><\/div><\/div><div class=\"x-container max width e6314-e86 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-2 e6314-e87 m4ve-4\"><div class=\"x-text x-content e6314-e88 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Extraits de la vid&eacute;o :<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>L&rsquo;Etat a pris la cause de ceux-l&agrave; qui nous vendent les semences, qui nous importent les semences pour s&rsquo;enrichir.&nbsp;<\/em><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>Normalement, si la graine est bonne, on vous la donne une fois pour toute, c&rsquo;est notre culture&nbsp;; c&rsquo;est culturel chez l&rsquo;agriculteur.<\/em><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>Au lieu de ma&icirc;triser notre semence, on finit par les semences qui nous ma&icirc;trisent&nbsp;; et &ccedil;a cela va devenir vraiment grave.<\/em><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>Nous manquons cruellement d&rsquo;information.<\/em>&nbsp;En RDC, CONAPAC et autres FOPAC (Associations de F&eacute;d&eacute;ration des agriculteurs de la RDC) sont en difficult&eacute; de produire des dossiers techniques ou politiques&hellip;<\/span><\/li>\n<\/ul><\/div><\/div><div class=\"x-column x-sm x-1-2 e6314-e89 m4ve-4\"><div class=\"x-text x-content e6314-e90 m4ve-7\"><iframe loading=\"lazy\" src=\"\/\/www.dailymotion.com\/embed\/video\/xs9trf\" width=\"480\" height=\"270\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div><div class=\"x-text x-content e6314-e91 m4ve-7\"><ul>\n<li style=\"text-align: justify;\"><span style=\"color: #05013c;\"><em>Si tu n&rsquo;as pas ta propre semence ou si tu ne sais pas o&ugrave; en trouver, tu finis par aller prendre des hybrides<\/em><\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Face &agrave; ces puissants,&nbsp;des personnes r&eacute;sistent dans le Monde et en Afrique, ici, des agriculteurs du Burkina Faso<\/span><\/p><\/div><\/div><\/div><div class=\"x-container max width e6314-e92 m4ve-1 m4ve-2\"><div class=\"x-column x-sm x-1-1 e6314-e93 m4ve-4\"><div class=\"x-text x-content e6314-e94 m4ve-7\"><h1><span style=\"color: #800000; font-size: 42px;\">L'agro&eacute;cologie est le futur de l'agriculture !<\/span><\/h1><\/div><div class=\"x-text x-content e6314-e95 m4ve-7\"><p style=\"text-align: justify;\"><span style=\"color: #05013c;\">Le 27 octobre 2015, la soci\u00e9t\u00e9 civile africaine fait une d\u00e9claration par laquelle il est temps de reconna\u00eetre que l'agro \u00e9cologie est le futur de l'agriculture en Afrique !\u00a0<a href=\"http:\/\/m.greenpeace.org\/switzerland\/fr\/high\/publications\/blog\/blockbuster-syngenta\/blog\/53916\/\" target=\"_blank\" rel=\"noopener\">Greenpeace Suisse<\/a>\u00a0:<\/span><\/p><\/div><div class=\"x-text x-content e6314-e96 m4ve-7\"><p><div id=\"x-content-band-3\" class=\"x-content-band bg-image parallax border-top border-left border-right border-bottom\" data-x-element=\"content_band\" data-x-params=\"{&quot;type&quot;:&quot;image&quot;,&quot;parallax&quot;:true}\" style=\"background-image: url(http:\/\/thierryregards.eu\/wp-content\/uploads\/2015\/06\/060212-104.jpg); background-color: transparent; color: #fff;\"><div class=\"x-container max width\"><em><strong><span style=\"color: #ffff00;\">Des mod\u00e8les de production innovants et \u00e9cologiques doivent remettre chaque personne au centre. <\/span><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Il faut de la nourriture pour tous\u00a0\u2013\u00a0sans polluer l'environnement, sans exposer les humains et les animaux \u00e0 des produits chimiques et des animaux inutiles, sans monocultures intensives, sans pertes de biodiversit\u00e9. Les paysans ne doivent pas simplement \u00eatre des travailleurs agricoles, mais des sp\u00e9cialistes qui soignent les bases de notre existence et produisent des aliments sains. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>L'agriculture \u00e9cologique prot\u00e8ge la biodiversit\u00e9 au lieu de la d\u00e9truire. Elle relie l'innovation scientifique et le savoir des paysans locaux.<\/em><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #ffff00;\"><strong>L'agriculture \u00e9cologique est moderne, elle se base sur la relation entre vous et les paysans. Et sur la relation avec la nature.<\/strong> <\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em>L'agriculture \u00e9cologique r\u00e9unit la science et l'innovation \u00e0 la biodiversit\u00e9. Elle contribue au d\u00e9veloppement des campagnes et assure la s\u00e9curit\u00e9 alimentaire.\u00a0Les paysans bio respectent les cycles naturels, prot\u00e8gent nos ressources, les abeilles et d'autres pollinisateurs importants. Ils nous fournissent en outre des aliments sains et savoureux.<\/em><\/div><\/div><\/p><\/div><div class=\"x-text x-content e6314-e97 m4ve-7\"><p style=\"text-align: justify;\"><strong><span style=\"color: #05013c;\">Tous les articles consacr\u00e9s aux<\/span> <\/strong><a href=\"http:\/\/thierryregards.eu\/en\/rdc-pais\/\" target=\"_blank\" rel=\"noopener\">Parcs Agro-Industriels<\/a><\/p><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Les porteurs du projet&nbsp;&laquo; D&eacute;pendance alimentaire &raquo;La cr\u00e9ation des parcs agro industriels est LA solution au probl\u00e8me de souverainet\u00e9 alimentaire envisag\u00e9e par le Pr\u00e9sident Joseph Kabila et son Premier ministre, Matata Ponyo. Le probl\u00e8me avec l\u2019agro-industrie est\u00a0: Qu\u2019elle utilise des OGM, des intrants chimiques et quantit\u00e9s d\u2019additifs dont l\u2019impact n\u00e9gatif sur la justice sociale, l\u2019\u00e9conomie, l\u2019environnement, la sant\u00e9, est de &#8230; <\/p>\n<div><a href=\"https:\/\/thierryregards.eu\/en\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/\" class=\"more-link\">Read More<\/a><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100,101,261,107],"tags":[90,337,334,338,335,340,339,333,91,336],"class_list":["post-6314","post","type-post","status-publish","format-standard","hentry","category-agriculture","category-parcs-agro-industriels","category-politque","category-rdc-les-possibles","tag-agriculture","tag-bill-gates","tag-comesa","tag-eu","tag-gma","tag-harvest","tag-iita","tag-les-complices","tag-parc-agro-industriel-pai","tag-usaid","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RDC - PAI - Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &amp; Cie - Thierryregards.eu<\/title>\n<meta name=\"description\" content=\"Les PAI soutenus par les lobbies COMESA-GMA-USAID-Bill Gates-UE-IITA-Harvest plus ont pour seul but la rentabilit\u00e9 financi\u00e8re (hauts salaires, dividendes)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thierryregards.eu\/en\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RDC - PAI - Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &amp; Cie - Thierryregards.eu\" \/>\n<meta property=\"og:description\" content=\"Les PAI soutenus par les lobbies COMESA-GMA-USAID-Bill Gates-UE-IITA-Harvest plus ont pour seul but la rentabilit\u00e9 financi\u00e8re (hauts salaires, dividendes)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thierryregards.eu\/en\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/\" \/>\n<meta property=\"og:site_name\" content=\"Thierryregards.eu\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-03T13:19:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T08:09:18+00:00\" \/>\n<meta name=\"author\" content=\"Thierry Carton de Tournai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thierry Carton de Tournai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/\"},\"author\":{\"name\":\"Thierry Carton de Tournai\",\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/#\\\/schema\\\/person\\\/c2cbd41e2ac19de18536c08c15f7cd28\"},\"headline\":\"RDC &#8211; PAI &#8211; Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &#038; Cie\",\"datePublished\":\"2015-03-03T13:19:12+00:00\",\"dateModified\":\"2024-08-02T08:09:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/\"},\"wordCount\":5618,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/#\\\/schema\\\/person\\\/c2cbd41e2ac19de18536c08c15f7cd28\"},\"keywords\":[\"Agriculture\",\"Bill Gates\",\"COMESA\",\"EU\",\"GMA\",\"Harvest\",\"IITA\",\"Les complices\",\"Parc agro industriel - PAI\",\"USAID\"],\"articleSection\":[\"Agriculture\",\"Parcs Agro Industriels\",\"Politique\",\"RDC...\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/\",\"url\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/\",\"name\":\"RDC - PAI - Les complices COMESA GMA USAID Bill Gates EU IITA Harvest & Cie - Thierryregards.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/#website\"},\"datePublished\":\"2015-03-03T13:19:12+00:00\",\"dateModified\":\"2024-08-02T08:09:18+00:00\",\"description\":\"Les PAI soutenus par les lobbies COMESA-GMA-USAID-Bill Gates-UE-IITA-Harvest plus ont pour seul but la rentabilit\u00e9 financi\u00e8re (hauts salaires, dividendes)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/2015\\\/03\\\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thierryregards.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RDC &#8211; PAI &#8211; Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &#038; Cie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/#website\",\"url\":\"https:\\\/\\\/thierryregards.eu\\\/\",\"name\":\"Thierry Regards sur la Soci\u00e9t\u00e9\",\"description\":\"Regards sur la Soci\u00e9t\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/#\\\/schema\\\/person\\\/c2cbd41e2ac19de18536c08c15f7cd28\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thierryregards.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/#\\\/schema\\\/person\\\/c2cbd41e2ac19de18536c08c15f7cd28\",\"name\":\"Thierry Carton de Tournai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Thierry-2019-.jpg\",\"url\":\"https:\\\/\\\/thierryregards.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Thierry-2019-.jpg\",\"contentUrl\":\"https:\\\/\\\/thierryregards.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Thierry-2019-.jpg\",\"width\":392,\"height\":458,\"caption\":\"Thierry Carton de Tournai\"},\"logo\":{\"@id\":\"https:\\\/\\\/thierryregards.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Thierry-2019-.jpg\"},\"description\":\"Regards sur la soci\u00e9t\u00e9 est une mani\u00e8re de m'exprimer autour de ces enjeux, avec modestie...\",\"sameAs\":[\"https:\\\/\\\/thierryregards.eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RDC - PAI - Les complices COMESA GMA USAID Bill Gates EU IITA Harvest & Cie - Thierryregards.eu","description":"Les PAI soutenus par les lobbies COMESA-GMA-USAID-Bill Gates-UE-IITA-Harvest plus ont pour seul but la rentabilit\u00e9 financi\u00e8re (hauts salaires, dividendes)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thierryregards.eu\/en\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/","og_locale":"en_US","og_type":"article","og_title":"RDC - PAI - Les complices COMESA GMA USAID Bill Gates EU IITA Harvest & Cie - Thierryregards.eu","og_description":"Les PAI soutenus par les lobbies COMESA-GMA-USAID-Bill Gates-UE-IITA-Harvest plus ont pour seul but la rentabilit\u00e9 financi\u00e8re (hauts salaires, dividendes)","og_url":"https:\/\/thierryregards.eu\/en\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/","og_site_name":"Thierryregards.eu","article_published_time":"2015-03-03T13:19:12+00:00","article_modified_time":"2024-08-02T08:09:18+00:00","author":"Thierry Carton de Tournai","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Thierry Carton de Tournai","Est. reading time":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/#article","isPartOf":{"@id":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/"},"author":{"name":"Thierry Carton de Tournai","@id":"https:\/\/thierryregards.eu\/#\/schema\/person\/c2cbd41e2ac19de18536c08c15f7cd28"},"headline":"RDC &#8211; PAI &#8211; Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &#038; Cie","datePublished":"2015-03-03T13:19:12+00:00","dateModified":"2024-08-02T08:09:18+00:00","mainEntityOfPage":{"@id":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/"},"wordCount":5618,"commentCount":1,"publisher":{"@id":"https:\/\/thierryregards.eu\/#\/schema\/person\/c2cbd41e2ac19de18536c08c15f7cd28"},"keywords":["Agriculture","Bill Gates","COMESA","EU","GMA","Harvest","IITA","Les complices","Parc agro industriel - PAI","USAID"],"articleSection":["Agriculture","Parcs Agro Industriels","Politique","RDC..."],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/","url":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/","name":"RDC - PAI - Les complices COMESA GMA USAID Bill Gates EU IITA Harvest & Cie - Thierryregards.eu","isPartOf":{"@id":"https:\/\/thierryregards.eu\/#website"},"datePublished":"2015-03-03T13:19:12+00:00","dateModified":"2024-08-02T08:09:18+00:00","description":"Les PAI soutenus par les lobbies COMESA-GMA-USAID-Bill Gates-UE-IITA-Harvest plus ont pour seul but la rentabilit\u00e9 financi\u00e8re (hauts salaires, dividendes)","breadcrumb":{"@id":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thierryregards.eu\/2015\/03\/rdc-drc-pai-complices-comesa-gma-usaid-bill-gates-eu-iita-harvest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thierryregards.eu\/"},{"@type":"ListItem","position":2,"name":"RDC &#8211; PAI &#8211; Les complices COMESA GMA USAID Bill Gates EU IITA Harvest &#038; Cie"}]},{"@type":"WebSite","@id":"https:\/\/thierryregards.eu\/#website","url":"https:\/\/thierryregards.eu\/","name":"Thierry Regards sur la Soci\u00e9t\u00e9","description":"Regards sur la Soci\u00e9t\u00e9","publisher":{"@id":"https:\/\/thierryregards.eu\/#\/schema\/person\/c2cbd41e2ac19de18536c08c15f7cd28"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thierryregards.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/thierryregards.eu\/#\/schema\/person\/c2cbd41e2ac19de18536c08c15f7cd28","name":"Thierry Carton de Tournai","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thierryregards.eu\/wp-content\/uploads\/2021\/12\/Thierry-2019-.jpg","url":"https:\/\/thierryregards.eu\/wp-content\/uploads\/2021\/12\/Thierry-2019-.jpg","contentUrl":"https:\/\/thierryregards.eu\/wp-content\/uploads\/2021\/12\/Thierry-2019-.jpg","width":392,"height":458,"caption":"Thierry Carton de Tournai"},"logo":{"@id":"https:\/\/thierryregards.eu\/wp-content\/uploads\/2021\/12\/Thierry-2019-.jpg"},"description":"Regards sur la soci\u00e9t\u00e9 est une mani\u00e8re de m'exprimer autour de ces enjeux, avec modestie...","sameAs":["https:\/\/thierryregards.eu"]}]}},"brizy_media":[],"_links":{"self":[{"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/posts\/6314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/comments?post=6314"}],"version-history":[{"count":6,"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/posts\/6314\/revisions"}],"predecessor-version":[{"id":17721,"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/posts\/6314\/revisions\/17721"}],"wp:attachment":[{"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/media?parent=6314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/categories?post=6314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thierryregards.eu\/en\/wp-json\/wp\/v2\/tags?post=6314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}